{"id":14200,"date":"2022-12-01T14:50:47","date_gmt":"2022-12-01T17:50:47","guid":{"rendered":"https:\/\/ceak.org.br\/ceak\/?p=14200"},"modified":"2025-10-28T18:54:42","modified_gmt":"2025-10-28T21:54:42","slug":"sua-doacao-transformando-vidas","status":"publish","type":"post","link":"https:\/\/ceak.org.br\/ceak\/sua-doacao-transformando-vidas\/","title":{"rendered":"Sua doa\u00e7\u00e3o transformando vidas!"},"content":{"rendered":"[vc_row][vc_column][vc_column_text]\n<p><strong>Com a proximidade da entrega da declara\u00e7\u00e3o do Imposto de Renda, voc\u00ea tem a oportunidade de ajudar <\/strong><strong>a Casa de Apoio \u00e0 Vida, Departamento do Centro Esp\u00edrita Allan Kardec!<\/strong><\/p>\n<div>\n<p><strong>A miss\u00e3o da CAVI\u00a0\u00e9 ser\u00a0refer\u00eancia no acolhimento, apoio e orienta\u00e7\u00e3o \u00e0s gestantes em situa\u00e7\u00e3o de vulnerabilidade e risco social<\/strong>, propiciando-lhes a\u00e7\u00f5es preventivas e protetivas de seus direitos fundamentais, al\u00e9m de capacit\u00e1-las para o mercado de trabalho.\u00a0<strong>Sua ajuda \u00e9 fundamental para impactar a vida de centenas de mam\u00e3es e seus beb\u00eas!<\/strong><\/p>\n<\/div>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph -->Siga o passo a passo abaixo\u00a0<strong>at\u00e9 29 de dezembro<\/strong>\u00a0e fa\u00e7a sua doa\u00e7\u00e3o!<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><strong>Quem pode doar?<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><strong>Pessoa F\u00edsica:<\/strong> quem declara pelo modelo completo pode destinar para a CAVI at\u00e9 6% do imposto devido por ano (calend\u00e1rio 1 de janeiro a 31 de dezembro).<\/p>\n<p>IR devido: o valor doado ser\u00e1 subtra\u00eddo da quantia a pagar.<\/p>\n<p>IR a restituir: o valor doado ser\u00e1 somado a sua restitui\u00e7\u00e3o.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><strong>Pessoa Jur\u00eddica:<\/strong>\u00a0quem apura o imposto de renda devido com base no Lucro Real\u00a0<strong>pode destinar para o CEAK at\u00e9 1% do imposto de renda devido.<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph {\"backgroundColor\":\"pale-cyan-blue\"} --><\/p>\n<p class=\"has-pale-cyan-blue-background-color has-background\"><strong>1\u00b0 Passo: C\u00e1lculo de Valores (Pessoa F\u00edsica)<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph -->Para calcular o valor que pode ser direcionado, \u00e9 conveniente fazer uma estimativa baseada no seu \u00faltimo Recibo de Entrega de Declara\u00e7\u00e3o. Caso seus rendimentos n\u00e3o forem parecidos com o ano anterior, voc\u00ea pode calcular seu potencial exato a partir do\u00a0<a href=\"https:\/\/u1823094.ct.sendgrid.net\/ls\/click?upn=hPYrwxPE9t9WQdDafobTCixPP-2BZ76jnKoJat26KbQAYN2Wvvvq0D4Ml4zyI-2BeicbP8c3AN2JMmxJwKG7zGKRTw-3D-3DgM1l_teUpoUEouv1PFf-2BShOzaa77eXnptUph1DkeftCBX9f8gNo9mp9leDIkAqnOp7i74g8iU6s-2B9qGvd-2FR0ktYAlwRzbt7ZL9lg-2BmOLq-2BRXoImqwH5C9DJyMkvDCxO9T1hLVphYGH7T5T-2BTr2Brkj4Hdjjcj8TWUOlIlCy3xVFvP4T6jmOcsi8ZYuIJG8HCbVog1JgFwOKB7GFgHsCseVnsmj1N6odtPTV5TjpxjUeP0fvw-3D\" target=\"_blank\" rel=\"noreferrer noopener\">Simulador da Receita Federal<\/a>.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph -->Usando como base os valores indicados nas linhas do Imposto de Renda Devido, calcule o valor m\u00e1ximo (6% do IR devido) que poder\u00e1 ser direcionado com isen\u00e7\u00e3o fiscal.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph {\"backgroundColor\":\"pale-cyan-blue\"} --><\/p>\n<p class=\"has-pale-cyan-blue-background-color has-background\"><strong>2\u00b0 Passo: Como doar<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:list --><\/p>\n<ul>\n<li>1. Acesse o site do Fundo Municipal:\u00a0<a href=\"http:\/\/fmdca.campinas.sp.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">fmdca.campinas.sp.gov.br<\/a>;<\/li>\n<li>2. Fa\u00e7a o cadastro (se j\u00e1 for cadastrado \u00e9 s\u00f3 fazer o login) e acesse a \u201c\u00c1rea do Destinador\u201d;<\/li>\n<li>3. Clique em \u201cNova Destina\u00e7\u00e3o\u201d;<\/li>\n<li>4. Aparecer\u00e1 \u201cDestina\u00e7\u00e3o beneficiando: FMDCA &#8211; FUNDO MUNICIPAL DOS DIREITOS DA CRIAN\u00c7A E DO ADOLESCENTE\u201d;<\/li>\n<li>5. Digite o valor que voc\u00ea deseja destinar e clique em \u201cConfirmar\u201d;<\/li>\n<li>6. Imprima o boleto banc\u00e1rio online e fa\u00e7a o pagamento at\u00e9 29\/12\/2022.<\/li>\n<\/ul>\n<p><!-- \/wp:list --><\/p>\n<p><!-- wp:paragraph --><strong>Importante: Ap\u00f3s o pagamento \u00e9 fundamental que voc\u00ea envie uma c\u00f3pia do boleto juntamente com o comprovante para\u00a0<a href=\"mailto:doadores@ceak.org.br\" target=\"_blank\" rel=\"noreferrer noopener\">doadores@ceak.org.br<\/a>, informando nome completo, CPF, valor da doa\u00e7\u00e3o e manifestar o desejo que sua\u00a0doa\u00e7\u00e3o seja feita para o CEAK &#8211; Casa de Apoio \u00e0 Vida.<\/strong><\/p>\n<p><i>Destina\u00e7\u00e3o de Imposto de Renda para entidades n\u00e3o-governamentais conforme Resolu\u00e7\u00e3o\u00a0n\u00ba 059\/2022. Para acessar o documento,\u00a0<a href=\"https:\/\/u1823094.ct.sendgrid.net\/ls\/click?upn=UPQANMCc2g50qDJZtO7jF0AbX9EJAmlIHN2BDw-2BBbCM-3DUTwF_teUpoUEouv1PFf-2BShOzaa77eXnptUph1DkeftCBX9f-2BvEyPTMk-2BMBny91G55BorICH2WW3-2BexVBlgQeiMfoHHAiBX8L0A-2FS-2Feku35LpuJ-2FWzdjgbQy83EbvE3EvdM2a4b8OC6dXii39ugRXzjce49qF4p7x5FAlwd4M8ElaGOT8Y-2BhTB4x2g6zL8DbpwLzTACjKgAW6RxtteY7gXXxj-2B2Wtx7DRXtSR8f63toMsSvJ4-3D\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/u1823094.ct.sendgrid.net\/ls\/click?upn%3DUPQANMCc2g50qDJZtO7jF0AbX9EJAmlIHN2BDw-2BBbCM-3DUTwF_teUpoUEouv1PFf-2BShOzaa77eXnptUph1DkeftCBX9f-2BvEyPTMk-2BMBny91G55BorICH2WW3-2BexVBlgQeiMfoHHAiBX8L0A-2FS-2Feku35LpuJ-2FWzdjgbQy83EbvE3EvdM2a4b8OC6dXii39ugRXzjce49qF4p7x5FAlwd4M8ElaGOT8Y-2BhTB4x2g6zL8DbpwLzTACjKgAW6RxtteY7gXXxj-2B2Wtx7DRXtSR8f63toMsSvJ4-3D&amp;source=gmail&amp;ust=1671288624191000&amp;usg=AOvVaw0FQNgCrmENoel2q6zmcARW\">clique aqui<\/a>.<\/i><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p>Se houver alguma d\u00favida, por favor nos avise. <br \/>Obrigado por nos apoiar sempre!\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph -->Um grande abra\u00e7o,<br \/><em>Equipe CEAK<\/em><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"align\":\"left\",\"id\":6804,\"width\":278,\"height\":198,\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"className\":\"is-style-default\"} --><\/p>\n<div class=\"wp-block-image is-style-default\">\u00a0<\/div>\n<p><!-- \/wp:image --><\/p>\n<p>&nbsp;<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_column_text] Com a proximidade da entrega da declara\u00e7\u00e3o do Imposto de Renda, voc\u00ea tem a oportunidade de ajudar a Casa de Apoio \u00e0 Vida, Departamento do Centro Esp\u00edrita Allan Kardec! A miss\u00e3o da CAVI\u00a0\u00e9 ser\u00a0refer\u00eancia no acolhimento, apoio e orienta\u00e7\u00e3o \u00e0s gestantes em situa\u00e7\u00e3o de vulnerabilidade e risco social, propiciando-lhes a\u00e7\u00f5es preventivas e protetivas de [&hellip;]\n","protected":false},"author":2,"featured_media":14326,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[38],"tags":[],"_links":{"self":[{"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/posts\/14200"}],"collection":[{"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/comments?post=14200"}],"version-history":[{"count":6,"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/posts\/14200\/revisions"}],"predecessor-version":[{"id":14325,"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/posts\/14200\/revisions\/14325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/media\/14326"}],"wp:attachment":[{"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/media?parent=14200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/categories?post=14200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceak.org.br\/ceak\/wp-json\/wp\/v2\/tags?post=14200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}