{"id":1481,"date":"2021-08-10T22:39:41","date_gmt":"2021-08-11T01:39:41","guid":{"rendered":"https:\/\/ceak.org.br\/ee\/?p=1481"},"modified":"2021-08-10T22:39:42","modified_gmt":"2021-08-11T01:39:42","slug":"visitando-capitulos-nada-agradaveis-da-nossa-historia","status":"publish","type":"post","link":"https:\/\/ceak.org.br\/ee\/visitando-capitulos-nada-agradaveis-da-nossa-historia\/","title":{"rendered":"Visitando cap\u00edtulos (nada agrad\u00e1veis) da nossa hist\u00f3ria"},"content":{"rendered":"<p>Ol\u00e1, Pessoal!!<\/p>\n<p>Aqui \u00e9 Ozzi, educador social no CCII e estou de volta pra mais uma atividade do nosso blog!<\/p>\n<p>Bem, o m\u00eas de agosto reserva muita informa\u00e7\u00e3o e troca de ideias no nosso bate papo. Vamos nos desdobrar em assuntos como <em>cidadania, direitos e participa\u00e7\u00e3o pol\u00edtica<\/em>, <strong>mas<em> calma!<\/em><\/strong> N\u00e3o precisa se entediar, tudo isso pode ser muito interessante e vai contribuir de forma muito positiva para nossa constru\u00e7\u00e3o.<\/p>\n<p>Estive estudando um pouco e trouxe sugest\u00f5es para potencializar nosso pensamento cr\u00edtico, entendendo de que forma nosso pa\u00eds carrega marcas e constru\u00e7\u00f5es de s\u00e9culos passados. Independente de g\u00eanero, ra\u00e7a, religi\u00e3o ou orienta\u00e7\u00e3o sexual; revisitar nossa hist\u00f3ria \u00e9 conscientizar-se e despertar para aspectos da atualidade, nos tornando seres cada vez mais ativos politicamente.<\/p>\n<p><strong><em>Na moral! Convida algu\u00e9m a\u00ed pra aprender junto contigo, informa\u00e7\u00e3o \u00e9 riqueza! Bora l\u00e1:<\/em><\/strong><\/p>\n<p><em><strong>Certo, nossa primeira parada \u00e9 nesse v\u00eddeo que explica um pouco da escravid\u00e3o no Brasil:<\/strong><\/em><\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"HIST\u00d3RIA DA ESCRAVID\u00c3O | QUER QUE DESENHE | MAPA MENTAL | DESCOMPLICA\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/lAbslmtscRk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div>\n<\/figure>\n<p><em><strong>Nosso segundo v\u00eddeo traz informa\u00e7\u00f5es sobre o Tr\u00e1fico Negreiro:<\/strong><\/em><\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"TR\u00c1FICO NEGREIRO \u2502 Hist\u00f3ria do Brasil .feat Pirula\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/TjcQTVLQDF0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div>\n<\/figure>\n<p><em><strong>Por fim, veremos um pouco sobre a Resist\u00eancia Negra:<\/strong><\/em><\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"RESISTENCIA NEGRA \u2502 Hist\u00f3ria do Brasil .feat Pirula\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/0fbUas21IEY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div>\n<\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"269\" height=\"100\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2016\/11\/logo-EE-1.png\" alt=\"\" class=\"wp-image-28\"\/><figcaption><strong><em>Nome do Evento: Atividade Virtual 20 CCII \u2013 Visitando cap\u00edtulos (nada agrad\u00e1veis) da nossa hist\u00f3ria.<br \/>Respons\u00e1veis: Ozieliton Santos \/ CCII Educand\u00e1rio Eur\u00edpedes<\/em><\/strong><br \/>\u00a0<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, Pessoal!! Aqui \u00e9 Ozzi, educador social no CCII e estou de volta pra mais uma atividade do nosso blog! Bem, o m\u00eas de agosto reserva muita informa\u00e7\u00e3o e troca de ideias no nosso bate papo. Vamos nos desdobrar em assuntos como cidadania, direitos e participa\u00e7\u00e3o pol\u00edtica, mas calma! N\u00e3o precisa se entediar, tudo isso [&hellip;]\n","protected":false},"author":3,"featured_media":1482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[22,36,20],"tags":[],"_links":{"self":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/1481"}],"collection":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/comments?post=1481"}],"version-history":[{"count":2,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/1481\/revisions"}],"predecessor-version":[{"id":1484,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/1481\/revisions\/1484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media\/1482"}],"wp:attachment":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media?parent=1481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/categories?post=1481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/tags?post=1481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}