{"id":1963,"date":"2022-12-16T18:33:45","date_gmt":"2022-12-16T20:33:45","guid":{"rendered":"https:\/\/ceak.org.br\/ee\/?p=1963"},"modified":"2022-12-16T18:35:58","modified_gmt":"2022-12-16T20:35:58","slug":"atividades-socioeducativas-para-o-fortalecimento-de-vinculos-e-de-habilidades","status":"publish","type":"post","link":"https:\/\/ceak.org.br\/ee\/atividades-socioeducativas-para-o-fortalecimento-de-vinculos-e-de-habilidades\/","title":{"rendered":"Atividades socioeducativas para o fortalecimento de v\u00ednculos e de habilidades!"},"content":{"rendered":"<p>O Centros de Conviv\u00eancia \u2013 CCII CEAK EE \u00e9 um espa\u00e7o que promove atividades em grupo desde os adolescentes&nbsp;at\u00e9 os idosos. T\u00eam o objetivo de fortalecer v\u00ednculos, assegurar a conviv\u00eancia e prevenir situa\u00e7\u00f5es de risco social. Al\u00e9m das atividades intergeracionais, as oficinas espec\u00edficas para o p\u00fablico adulto e idoso acontecem \u00e0s quintas-feiras no per\u00edodo da tarde.<\/p>\n<p>Dentre as atividades desenvolvidas pelos grupos de adultos, destacam-se as atividades art\u00edsticas, que funcionam como estrat\u00e9gia para promover a conviv\u00eancia e a ressignifica\u00e7\u00e3o de experi\u00eancias vivenciadas pelos usu\u00e1rios. Dentre elas, temos as oficinas de Artes Manuais, que busca despertar a criatividade.<\/p>\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"457\" height=\"812\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/image.png\" alt=\"\" class=\"wp-image-1964 size-full\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/image.png 457w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/image-450x800.png 450w\" sizes=\"(max-width: 457px) 100vw, 457px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<p>Aproveitamos este valioso momento para resgatar mem\u00f3rias art\u00edsticas&nbsp;como&nbsp;uma forma&nbsp;terap\u00eautica, pois convida as pessoas a mergulharem em si mesmas e trazer \u00e0 tona suas habilidades, qualidades, medos, desejos e diversos aspectos de seu consciente e inconsciente.<\/p>\n<p>Nosso p\u00fablico adulto&nbsp;participou do&nbsp;processo criativo na oficina de vasinhos decorados. Nesta oficina pudemos criar desenhos e pinturas em vasos&nbsp;de plantas, saindo da ideia de um vaso de pl\u00e1stico simples&nbsp;para um objeto criativo pintado com cores variadas.&nbsp; Ap\u00f3s pintarmos, plantamos a semente de tomate e cada um levou e cultivou em sua casa. &nbsp;Resultado logo&nbsp;apareceu e a nossa educanda C\u00e9lia fotografou e nos enviou, confiram \u2026<\/p>\n<p><em>&#8220;Foi uma atividade, onde pude pintar meu pr\u00f3prio vasinho, isto \u00e9 literalmente pus a m\u00e3o na massa (no caso no vaso), foi excelente\u201d.&nbsp;&nbsp;&nbsp;<\/em><\/p>\n<\/div>\n<\/div>\n<figure class=\"wp-block-gallery columns-2 is-cropped\">\n<ul class=\"blocks-gallery-grid\">\n<li class=\"blocks-gallery-item\">\n<figure><img loading=\"lazy\" width=\"720\" height=\"1280\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/BLOG-Artes-Manuais-2-1.jpg\" alt=\"\" data-id=\"1966\" data-full-url=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/BLOG-Artes-Manuais-2-1.jpg\" data-link=\"https:\/\/ceak.org.br\/ee\/?attachment_id=1966#main\" class=\"wp-image-1966\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/BLOG-Artes-Manuais-2-1.jpg 720w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/BLOG-Artes-Manuais-2-1-450x800.jpg 450w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/BLOG-Artes-Manuais-2-1-600x1067.jpg 600w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n<\/li>\n<li class=\"blocks-gallery-item\">\n<figure><img loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/BLOG-Artes-Manuais-red.jpg\" alt=\"\" data-id=\"1967\" data-full-url=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/BLOG-Artes-Manuais-red.jpg\" data-link=\"https:\/\/ceak.org.br\/ee\/?attachment_id=1967#main\" class=\"wp-image-1967\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/BLOG-Artes-Manuais-red.jpg 900w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/BLOG-Artes-Manuais-red-600x800.jpg 600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2022\/12\/BLOG-Artes-Manuais-red-768x1024.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/li>\n<\/ul>\n<\/figure>\n<blockquote class=\"wp-block-quote\"><p>\n<em>\u201cTive o privil\u00e9gio de ter em m\u00e3os meu primeiro vaso pintado por mim, foi incr\u00edvel agora o mais sensacional foi quando o esse vaso deu vida\u00a0ao meu 1\u00b0 p\u00e9 de tomate, tive o gostinho de semana ap\u00f3s semana de reg\u00e1-lo e agora de um pequeno pezinho, j\u00e1 virou um lindo pez\u00e3o de tomate. Com carinho em tudo, a gente faz com que as coisas aconte\u00e7am. Obrigada Thay pelo incentivo e como plantar\u201d.<\/em>\n<\/p><\/blockquote>\n<p><em>Quer saber mais sobre as atividades do CEAK Educand\u00e1rio Eur\u00edpedes? <\/em>Entre em contato pelo e-mail <a href=\"mailto:adm8.ee.cml@ceak.org.br\">adm8.ee.cml@ceak.org.br<\/a> ou pelo <em>WhatsApp<\/em> (19) 99433.3657.<\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"269\" height=\"100\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2016\/11\/logo-EE.png\" alt=\"\" class=\"wp-image-26\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O Centros de Conviv\u00eancia \u2013 CCII CEAK EE \u00e9 um espa\u00e7o que promove atividades em grupo desde os adolescentes&nbsp;at\u00e9 os idosos. T\u00eam o objetivo de fortalecer v\u00ednculos, assegurar a conviv\u00eancia e prevenir situa\u00e7\u00f5es de risco social. Al\u00e9m das atividades intergeracionais, as oficinas espec\u00edficas para o p\u00fablico adulto e idoso acontecem \u00e0s quintas-feiras no per\u00edodo da [&hellip;]\n","protected":false},"author":3,"featured_media":1968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[22,36],"tags":[],"_links":{"self":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/1963"}],"collection":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/comments?post=1963"}],"version-history":[{"count":2,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/1963\/revisions"}],"predecessor-version":[{"id":1971,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/1963\/revisions\/1971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media\/1968"}],"wp:attachment":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media?parent=1963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/categories?post=1963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/tags?post=1963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}