{"id":2147,"date":"2023-05-20T09:33:00","date_gmt":"2023-05-20T12:33:00","guid":{"rendered":"https:\/\/ceak.org.br\/ee\/?p=2147"},"modified":"2023-05-23T09:49:24","modified_gmt":"2023-05-23T12:49:24","slug":"soul-pizzaiolo-celebrando-mais-uma-conquista","status":"publish","type":"post","link":"https:\/\/ceak.org.br\/ee\/soul-pizzaiolo-celebrando-mais-uma-conquista\/","title":{"rendered":"Soul Pizzaiolo \u2013 Celebrando mais uma conquista!"},"content":{"rendered":"<p>No dia <em>13 de abril de 2023<\/em> realizamos no CEAK Educand\u00e1rio Eur\u00edpedes o encontro de encerramento das atividades do Projeto Soul Pizzaiolo. Ap\u00f3s 11 encontros com aprendizagem pr\u00e1tica e atividades socioeducativas, 17 adolescentes e jovens conclu\u00edram a participa\u00e7\u00e3o.<\/p>\n<p>Em conjunto com familiares, amigos, integrantes da equipe e do conselho do CEAK EE, representantes da empresa Alibra Ingredientes, parceira fundamental para o sucesso do projeto, celebramos um momento muito significativo, a conquista para os adolescentes e jovens do aprendizado e conhecimento adquirido.<\/p>\n<p>Compartilhamos a seguir os depoimentos que demonstram a import\u00e2ncia do trabalho realizado. Nossos agradecimentos os pais e respons\u00e1veis por confiarem no trabalho realizado na institui\u00e7\u00e3o e a Empresa Alibra Ingredientes, atrav\u00e9s da sua equipe, por apoiar a concretiza\u00e7\u00e3o de sonhos e qualifica\u00e7\u00e3o de futuros profissionais.<\/p>\n<figure class=\"wp-block-gallery columns-3 is-cropped\">\n<ul class=\"blocks-gallery-grid\">\n<li class=\"blocks-gallery-item\">\n<figure><img loading=\"lazy\" width=\"1600\" height=\"1067\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-1-1600x1067.jpg\" alt=\"\" data-id=\"2155\" data-full-url=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-1.jpg\" data-link=\"https:\/\/ceak.org.br\/ee\/?attachment_id=2155#main\" class=\"wp-image-2155\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-1-1600x1067.jpg 1600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-1-800x533.jpg 800w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-1-768x512.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-1-1536x1024.jpg 1536w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-1-600x400.jpg 600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-1.jpg 1620w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n<\/li>\n<li class=\"blocks-gallery-item\">\n<figure><img loading=\"lazy\" width=\"1600\" height=\"1067\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-3-1600x1067.jpg\" alt=\"\" data-id=\"2156\" data-full-url=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-3.jpg\" data-link=\"https:\/\/ceak.org.br\/ee\/?attachment_id=2156#main\" class=\"wp-image-2156\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-3-1600x1067.jpg 1600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-3-800x533.jpg 800w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-3-768x512.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-3-1536x1024.jpg 1536w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-3-600x400.jpg 600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-3.jpg 1620w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n<\/li>\n<li class=\"blocks-gallery-item\">\n<figure><img loading=\"lazy\" width=\"1600\" height=\"1067\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-10-1600x1067.jpg\" alt=\"\" data-id=\"2157\" data-full-url=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-10.jpg\" data-link=\"https:\/\/ceak.org.br\/ee\/?attachment_id=2157#main\" class=\"wp-image-2157\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-10-1600x1067.jpg 1600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-10-800x533.jpg 800w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-10-768x512.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-10-1536x1024.jpg 1536w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-10-600x400.jpg 600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-10.jpg 1620w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n<\/li>\n<\/ul>\n<\/figure>\n<p class=\"has-text-align-left\"><strong><em>Depoimentos:<\/em><\/strong><\/p>\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:36% auto\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-4-340x340.jpg\" alt=\"Leticia Nathiely Marques, 15 anos, participante do projeto.\" class=\"wp-image-2148 size-thumbnail\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-4-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-4-300x300.jpg 300w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-4-100x100.jpg 100w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<blockquote class=\"wp-block-quote is-style-default\"><p>\n\u201cMeu nome \u00e9 Let\u00edcia Natiele, tenho 15 anos e participei do projeto Soul Pizzaiolo da primeira turma. Hoje eu estou aqui para fazer um depoimento sobre esse per\u00edodo. Gostei muito de ter participado, pois aprendi v\u00e1rias coisas que eu nunca imaginei e ter oportunidade de aprender. Quero agradecer a toda a equipe da empresa Alibra e toda a equipe do Educand\u00e1rio Eur\u00edpedes por ter nos dado essa incr\u00edvel oportunidade. Meu plano para a vida profissional n\u00e3o \u00e9 seguir essa profiss\u00e3o, mas acredito que para quem quer isso para sua vida profissional, esse projeto ajudou muito, pois muitas pessoas t\u00eam um sonho de ser Pizzaiolo mas n\u00e3o tem dinheiro para conseguir fazer um curso ou\u00a0se aprofundar mais nesse assunto.\u00a0Tenho certeza que foi uma honra de todos os 17 jovens ter conseguido se inscrever e ter participado desse projeto. Todos os dias que estivemos no Educand\u00e1rio para aprender fazer as pizzas foram muito gratificantes, mas encerramento n\u00e3o tenho nem palavras para escrever, tanto que meu cora\u00e7\u00e3o estava feliz! Foi um dia super, mega especial ver todos os familiares de todos os colegas comendo a nossa pizza, elogiando a nossa conquista e vendo a gente receber nosso certificado. Tenho certeza que foi a melhor sensa\u00e7\u00e3o para todos os pais respons\u00e1veis e n\u00f3s\u00a0participantes do Soul Pizzaiolo. E hoje estou aqui com meu certificado com 91% de participa\u00e7\u00e3o, com o cortador de pizza, com o avental e minha touca. \u00c9 isso, s\u00f3 tenho a agradecer a todos voc\u00eas, obrigada Educand\u00e1rio e obrigada Alibra\u201d. <em>Leticia Nathiely Marques, 15 anos, participante do projeto.<\/em>\n<\/p><\/blockquote>\n<\/div>\n<\/div>\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"1001\" height=\"1502\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-5.jpg\" alt=\"\" class=\"wp-image-2149 size-full\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-5.jpg 1001w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-5-533x800.jpg 533w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-5-768x1152.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-5-600x900.jpg 600w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<blockquote class=\"wp-block-quote\"><p>\n\u201cEu lembro que fui em busca de um curso simples de p\u00e3es\u00a0e acabei me formando em um de pizza. Desde a minha entrada no Educand\u00e1rio, todos foram muito gentis, atenciosos, prestativos, me ajudaram, auxiliaram, me fizeram sentir como se j\u00e1 estivesse l\u00e1 desde pequena. O que tornou a experi\u00eancia do curso tudo melhor. Fiz amizades novas, que com certeza vou sentir saudades, aprendi receitas que vou levar para a vida toda. Aprendi valores importantes com a professora, aprendi que o mundo \u00e9 muito maior do que imaginamos, agrade\u00e7o muito a empresa Alibra, por ter patrocinado o curso t\u00e3o bom e t\u00e3o gostoso!! Cada aula, cada hora, cada minutinho que voou e eu nem vi passar, de um curso t\u00e3o incr\u00edvel que acabou t\u00e3o r\u00e1pido. Eu realmente agrade\u00e7o a todos pelo tempo que passaram me ensinando, agrade\u00e7o ao Zani tamb\u00e9m por ter ensinado algo que nunca irei esquecer, que uma pizza tem que ter 10 azeitonas. Muito obrigada !!!\u201d <em>Rebeca Rocha Carvalho de Oliveira, 17 anos, participante do projeto.<\/em>\n<\/p><\/blockquote>\n<\/div>\n<\/div>\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"780\" height=\"1040\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-6.jpeg\" alt=\"\" class=\"wp-image-2150 size-full\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-6.jpeg 780w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-6-600x800.jpeg 600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-6-768x1024.jpeg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<blockquote class=\"wp-block-quote\"><p>\n\u201cAgrade\u00e7o a toda equipe Educand\u00e1rio por ter disponibilizado esse curso maravilhoso e ter acolhido minha filha e toda essa garotada. Estou muito orgulhosa dela&#8230;sempre muito esfor\u00e7ada e dedicada em tudo que faz. Quero agradecer a oportunidade que voc\u00eas ofertaram com amor, carinho e aten\u00e7\u00e3o, que ela recebeu no curso e com todos os envolvidos. Muito obrigada de cora\u00e7\u00e3o. Deus aben\u00e7oe voc\u00eas\u201d. <em>Juliana Cristina Rocha de Carvalho, m\u00e3e da Rebeca Rocha.<\/em>\n<\/p><\/blockquote>\n<\/div>\n<\/div>\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"1067\" height=\"1600\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-9-1067x1600.jpg\" alt=\"Ary Almeida Prado \u2013 Conselho Gestor do CEAK EE\" class=\"wp-image-2151 size-full\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-9-1067x1600.jpg 1067w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-9-533x800.jpg 533w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-9-768x1152.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-9-1024x1536.jpg 1024w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-9-600x900.jpg 600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-9.jpg 1080w\" sizes=\"(max-width: 1067px) 100vw, 1067px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<p>\u201cO aprendizado \u00e9 um processo muito poderoso em nossa vida, pois nos motiva a conhecer melhor o mundo em que vivemos. Estudar \u00e9 fundamental para crescermos profissionalmente, possibilitando novas habilidades, portanto podendo tomar melhores decis\u00f5es, superar as nossas dificuldades e acima de tudo ser uma pessoa melhor. Por isso esse curso \u00e9 t\u00e3o importante para os nossos jovens. Atrav\u00e9s do estudo que adquirimos conhecimentos e tra\u00e7amos os nossos objetivos de vida.<\/p>\n<p>Espero que o Educand\u00e1rio Eur\u00edpedes e a Alibra possam fazer novas parcerias, sempre com objetivo de ajudar os nossos jovens a se desenvolverem e terem mais oportunidade na vida\u201d. <em>Ary Almeida Prado \u2013 Conselho Gestor do CEAK EE<\/em><\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"996\" height=\"1495\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-7.jpg\" alt=\"\" class=\"wp-image-2152 size-full\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-7.jpg 996w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-7-533x800.jpg 533w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-7-768x1153.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-7-600x901.jpg 600w\" sizes=\"(max-width: 996px) 100vw, 996px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<blockquote class=\"wp-block-quote\"><p>\n\u201cFoi uma honra promover este projeto em parceria com CEAK Educand\u00e1rio Eur\u00edpedes, que fez um trabalho fant\u00e1stico junto a estes jovens. O Soul Pizzaiolo proporcionou atividades de aprendizagem pr\u00e1tica, contribuiu para a forma\u00e7\u00e3o profissional, e estimulou o protagonismo e o trabalho em equipe. N\u00f3s, da Alibra, desejamos que esta experi\u00eancia tenha colaborado para o crescimento pessoal e profissional de cada um. Agradecemos a toda equipe do Educand\u00e1rio, em especial a Alzira, o Luiz e a Andrea, pelo empenho e dedica\u00e7\u00e3o para que este projeto fosse concretizado com sucesso\u201d. <em>Fabiano Copruchinski, Diretor da Alibra Ingredientes.<\/em>\n<\/p><\/blockquote>\n<\/div>\n<\/div>\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"1067\" height=\"1600\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-8-1067x1600.jpg\" alt=\"\" class=\"wp-image-2153 size-full\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-8-1067x1600.jpg 1067w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-8-533x800.jpg 533w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-8-768x1152.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-8-1024x1536.jpg 1024w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-8-600x900.jpg 600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/05\/Encerramento-Soul-Pizzaiolo-8.jpg 1080w\" sizes=\"(max-width: 1067px) 100vw, 1067px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<blockquote class=\"wp-block-quote\"><p>\n\u201cO Soul Pizzaiolo \u00e9 uma iniciativa da Alibra Ingredientes que tem como prop\u00f3sito ensinar a profiss\u00e3o a adolescentes e jovens, em um setor com grande demanda por m\u00e3o de obra e chances de progress\u00e3o na carreira, al\u00e9m de promover o desenvolvimento pessoal e estimular a criatividade, disciplina, comunica\u00e7\u00e3o e protagonismo. \u00c9 uma oportunidade para que os participantes aprendam a preparar pizzas na pr\u00e1tica com algumas de nossas solu\u00e7\u00f5es, como os queijos an\u00e1logos Mozzana e Mozzatet, excelentes alternativas para padronizar receitas com mussarela, proporcionando alta performance e rendimento. Para n\u00f3s, contar com a estrutura f\u00edsica do Educand\u00e1rio Eur\u00edpedes, e com seus servi\u00e7os especializados em projetos socioassistenciais nas \u00e1reas de coordena\u00e7\u00e3o t\u00e9cnica, administrativa e operacional \u00e9, sem d\u00favida, fundamental para o sucesso deste importante projeto social da Alibra\u201d. <em>Liliana Couto Bem-Haja, Gerente de Comunica\u00e7\u00e3o da Alibra Ingredientes.<\/em>\n<\/p><\/blockquote>\n<\/div>\n<\/div>\n<p><strong><em>Quer saber mais sobre as atividades do CEAK Educand\u00e1rio Eur\u00edpedes? Entre em contato pelo e-mail adm8.ee.cml@ceak.org.br ou pelo WhatsApp (19) 99433.3657.<\/em><\/strong><\/p>\n<p><em><strong>Nome do evento:<\/strong> Soul Pizzaiolo \u2013 Celebrando mais uma conquista! <strong>Respons\u00e1vel:<\/strong> Luiz Mendes e Alzira Praxedes.<\/em><\/p>\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/04\/2822-Logotipo-01-1600x1146.jpg\" alt=\"\" class=\"wp-image-2128\" width=\"303\" height=\"215\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>No dia 13 de abril de 2023 realizamos no CEAK Educand\u00e1rio Eur\u00edpedes o encontro de encerramento das atividades do Projeto Soul Pizzaiolo. Ap\u00f3s 11 encontros com aprendizagem pr\u00e1tica e atividades socioeducativas, 17 adolescentes e jovens conclu\u00edram a participa\u00e7\u00e3o. Em conjunto com familiares, amigos, integrantes da equipe e do conselho do CEAK EE, representantes da empresa [&hellip;]\n","protected":false},"author":3,"featured_media":2154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[22,7,15],"tags":[],"_links":{"self":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/2147"}],"collection":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/comments?post=2147"}],"version-history":[{"count":1,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/2147\/revisions"}],"predecessor-version":[{"id":2158,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/2147\/revisions\/2158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media\/2154"}],"wp:attachment":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media?parent=2147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/categories?post=2147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/tags?post=2147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}