{"id":2193,"date":"2023-07-21T17:50:55","date_gmt":"2023-07-21T20:50:55","guid":{"rendered":"https:\/\/ceak.org.br\/ee\/?p=2193"},"modified":"2023-07-21T18:06:55","modified_gmt":"2023-07-21T21:06:55","slug":"xv-conferencia-municipal-de-assistencia-social-2023","status":"publish","type":"post","link":"https:\/\/ceak.org.br\/ee\/xv-conferencia-municipal-de-assistencia-social-2023\/","title":{"rendered":"XV Confer\u00eancia Municipal de Assist\u00eancia Social 2023"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignright is-resized\"><img loading=\"lazy\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/AMANDA-scaled.jpg\" alt=\"\" class=\"wp-image-2194\" width=\"162\" height=\"243\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/AMANDA-scaled.jpg 1707w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/AMANDA-533x800.jpg 533w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/AMANDA-1067x1600.jpg 1067w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/AMANDA-768x1152.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/AMANDA-1024x1536.jpg 1024w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/AMANDA-1366x2048.jpg 1366w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/AMANDA-600x900.jpg 600w\" sizes=\"(max-width: 162px) 100vw, 162px\" \/><figcaption>Amanda G. Ribeiro<\/figcaption><\/figure>\n<\/div>\n<p class=\"has-text-align-left\">Como parte das estrat\u00e9gias metodol\u00f3gicas do CCII CEAK Educand\u00e1rio Eur\u00edpedes est\u00e1 a a\u00e7\u00e3o \u201c<strong><em>Informa\u00e7\u00e3o e comunica\u00e7\u00e3o sobre os direitos e formas para o seu acesso e reclama\u00e7\u00e3o<\/em><\/strong>\u201d. Em 2023, como uma das propostas para efetivar essa a\u00e7\u00e3o, foi a participa\u00e7\u00e3o na XV Confer\u00eancia Municipal de Assist\u00eancia Social. A seguir, o descritivo da Assistente Social do servi\u00e7o, Amanda Galindo Ribeiro, sobre a nossa participa\u00e7\u00e3o!<\/p>\n<p>Como profissional do Sistema \u00danico de Assist\u00eancia Social \u2013 SUAS \u00e9 a primeira participa\u00e7\u00e3o numa Confer\u00eancia de Assist\u00eancia Social. Considero um espa\u00e7o de mobiliza\u00e7\u00e3o social de extrema import\u00e2ncia para garantia e amplia\u00e7\u00e3o de direitos. Durante a prepara\u00e7\u00e3o, atrav\u00e9s de encontro formativo e Confer\u00eancia Regional em especial da regi\u00e3o norte, possibilitou discuss\u00f5es com profissionais atuantes do SUAS e as diversas dificuldades na execu\u00e7\u00e3o dos servi\u00e7os em especial pela defasagem do quadro profissional e recursos insuficientes para execu\u00e7\u00e3o dos servi\u00e7os ofertados de forma efetiva.<\/p>\n<p>Houve ressalvas com falas em especial dos usu\u00e1rios sobre os benef\u00edcios de transfer\u00eancia de renda que hoje a forma que \u00e9 ofertado dentro das vulnerabilidades sociais que s\u00e3o emergentes e diversas se tornam insuficientes, sendo necess\u00e1rio um olhar de cuidados dos dirigentes e nossos representantes. Durante todo o processo que participei verifiquei que houve organiza\u00e7\u00e3o e melhorias, entretanto gostaria de deixar dois relatos o site do CMAS n\u00e3o \u00e9 din\u00e2mico ou facilitador, pois as informa\u00e7\u00f5es n\u00e3o s\u00e3o atualizadas constantemente e os facilitadores dos eixos devem ser melhor direcionados para que n\u00e3o haja desorganiza\u00e7\u00e3o nas discuss\u00f5es de forma que todos (usu\u00e1rios, trabalhadores e ouvintes) sejam direcionados diante do objetivo principal.<\/p>\n<p>Algo que me fortaleceu foram as falas das usu\u00e1rias que entendem que ocupar estes espa\u00e7os s\u00e3o importantes e como esclarecidas sa\u00edram, sendo acolhidas por todo o grupo divididos em eixos que usu\u00e1rios estavam presente manifestando suas demandas e necessidades como ocupantes dos espa\u00e7os.<\/p>\n<p>A usu\u00e1ria Karen descreve:<\/p>\n<p>\u201cPrimeiramente, quero dizer que foi prazeroso vivenciar a 15\u00b0conferencia do SUAS, pois n\u00e3o tinha ideia de como e dificultoso os servi\u00e7os da assist\u00eancia social. Para mim, foi um aprendizado que jamais esquecerei. Tamb\u00e9m n\u00e3o posso deixar de dizer que sou participante desses servi\u00e7os. Apesar de n\u00e3o ser como gostaria que fosse esses servi\u00e7os sim s\u00e3o importante para nos quanto usu\u00e1rias(os). Vamos lutar para que o Suas que temos, n\u00e3o e o suas que queremos. Sem mais agrade\u00e7o por tudo\u201d.<\/p>\n<p>Em forma complementar da fala da usu\u00e1ria, relembro um momento em especial, pois no primeiro dia da Confer\u00eancia se falava muito das quest\u00f5es de trabalho dos profissionais, mas esqueceram de falar da ocupa\u00e7\u00e3o do usu\u00e1rio em especial para pensar na melhoria das Pol\u00edticas P\u00fablicas voltadas a eles, sendo um momento de discuss\u00e3o mais exaltada, sendo acolhidos pelos trabalhadores de Organiza\u00e7\u00e3o da Sociedade Civil \u2013 OSC e sentindo aus\u00eancia do setor p\u00fablico com direcionamento das quest\u00f5es de trabalho.<\/p>\n<p>A usu\u00e1ria Rose que esteve acompanhada do esposo, verbaliza que a Confer\u00eancia foi legal, pois conseguiu entender melhor seus direitos e conversar com outros usu\u00e1rios que utilizam diversos servi\u00e7os.<\/p>\n<figure class=\"wp-block-gallery columns-2\">\n<ul class=\"blocks-gallery-grid\">\n<li class=\"blocks-gallery-item\">\n<figure><img loading=\"lazy\" width=\"1280\" height=\"960\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-3.jpg\" alt=\"\" data-id=\"2197\" data-full-url=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-3.jpg\" data-link=\"https:\/\/ceak.org.br\/ee\/xv-conferencia-municipal-de-assistencia-social-2023\/foto-3-2\/#main\" class=\"wp-image-2197\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-3.jpg 1280w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-3-800x600.jpg 800w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-3-768x576.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-3-600x450.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n<\/li>\n<li class=\"blocks-gallery-item\">\n<figure><img loading=\"lazy\" width=\"1600\" height=\"1200\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-1-1.jpg\" alt=\"\" data-id=\"2198\" data-full-url=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-1-1.jpg\" data-link=\"https:\/\/ceak.org.br\/ee\/xv-conferencia-municipal-de-assistencia-social-2023\/foto-1-1\/#main\" class=\"wp-image-2198\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-1-1.jpg 1600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-1-1-800x600.jpg 800w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-1-1-768x576.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-1-1-1536x1152.jpg 1536w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-1-1-600x450.jpg 600w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n<\/li>\n<li class=\"blocks-gallery-item\">\n<figure><img loading=\"lazy\" width=\"1200\" height=\"1600\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-2-1.jpg\" alt=\"\" data-id=\"2199\" data-full-url=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-2-1.jpg\" data-link=\"https:\/\/ceak.org.br\/ee\/xv-conferencia-municipal-de-assistencia-social-2023\/foto-2-1\/#main\" class=\"wp-image-2199\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-2-1.jpg 1200w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-2-1-600x800.jpg 600w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-2-1-768x1024.jpg 768w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2023\/07\/Foto-2-1-1152x1536.jpg 1152w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/li>\n<\/ul>\n<\/figure>\n<p><strong><em>Quer saber mais sobre as atividades do CEAK Educand\u00e1rio Eur\u00edpedes? Entre em contato pelo e-mail adm8.ee.cml@ceak.org.br ou pelo WhatsApp (19) 99433.3657.<\/em><\/strong><\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"269\" height=\"100\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2016\/11\/logo-EE.png\" alt=\"\" class=\"wp-image-26\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Como parte das estrat\u00e9gias metodol\u00f3gicas do CCII CEAK Educand\u00e1rio Eur\u00edpedes est\u00e1 a a\u00e7\u00e3o \u201cInforma\u00e7\u00e3o e comunica\u00e7\u00e3o sobre os direitos e formas para o seu acesso e reclama\u00e7\u00e3o\u201d. Em 2023, como uma das propostas para efetivar essa a\u00e7\u00e3o, foi a participa\u00e7\u00e3o na XV Confer\u00eancia Municipal de Assist\u00eancia Social. A seguir, o descritivo da Assistente Social do [&hellip;]\n","protected":false},"author":3,"featured_media":2201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[22,20,7],"tags":[],"_links":{"self":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/2193"}],"collection":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/comments?post=2193"}],"version-history":[{"count":2,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/2193\/revisions"}],"predecessor-version":[{"id":2214,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/2193\/revisions\/2214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media\/2201"}],"wp:attachment":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media?parent=2193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/categories?post=2193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/tags?post=2193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}