{"id":499,"date":"2020-01-06T18:29:48","date_gmt":"2020-01-06T21:29:48","guid":{"rendered":"https:\/\/ceak.org.br\/ee\/?p=499"},"modified":"2020-01-06T18:45:19","modified_gmt":"2020-01-06T21:45:19","slug":"aprendizagem-profissional-a-garantia-do-direito","status":"publish","type":"post","link":"https:\/\/ceak.org.br\/ee\/aprendizagem-profissional-a-garantia-do-direito\/","title":{"rendered":"Aprendizagem Profissional \u2013 A Garantia do Direito!"},"content":{"rendered":"<p>Em conson\u00e2ncia com a Lei Federal 10.097\/2000, o\u00a0<strong>Educand\u00e1rio Eur\u00edpedes<\/strong>\u00a0realiza a\u00a0<strong>Aprendizagem Profissional de Adolescentes e Jovens<\/strong>\u00a0tendo como objetivo\u00a0<em>\u201catender adolescentes estudantes de escola p\u00fablica, e de fam\u00edlias de baixa renda e p\u00fablico priorit\u00e1rio, possibilitando a forma\u00e7\u00e3o t\u00e9cnico-profissional met\u00f3dica compat\u00edvel com seu desenvolvimento, f\u00edsico, moral e psicol\u00f3gico respeitando sua condi\u00e7\u00e3o peculiar de pessoa em desenvolvimento\u201d<\/em>.<\/p>\n<p>Durante o desenvolvimento das Atividades Te\u00f3ricas ao longo do ano de 2019 os educadores identificaram muitas habilidades dentre os adolescentes e jovens pouco exploradas. Foi ent\u00e3o que surgiu a ideia do\u00a0<strong>Festival de Artes<\/strong>\u00a0para que os aprendizes apresentassem de forma art\u00edstica suas habilidades e potencialidades.<\/p>\n<p>A primeira apresenta\u00e7\u00e3o aconteceu no dia 18 de Outubro entre os pr\u00f3prios aprendizes. A partir do sucesso do trabalho desenvolvido, a equipe sugeriu aos aprendizes repetir as apresenta\u00e7\u00f5es aos amigos, familiares e orientadores das Atividades Pr\u00e1ticas, contudo, de forma coletiva, envolvendo todos os aprendizes.<\/p>\n<p>E assim aconteceu!\u00a0<strong>No dia 16 de dezembro (segunda-feira)<\/strong>, na presen\u00e7a dos familiares, amigos e representantes das empresas parceiras, realizamos o\u00a0<strong><em>Encontro com Fam\u00edlias, Parceiros e Aprendizes<\/em><\/strong>\u00a0<strong>para celebrar as realiza\u00e7\u00f5es de 2019<\/strong>. Contamos com apresenta\u00e7\u00f5es musicais, dan\u00e7a e depoimentos dos aprendizes.<\/p>\n<p>Todo esse processo demonstra a import\u00e2ncia da\u00a0<strong>Aprendizagem Profissional<\/strong>\u00a0como uma estrat\u00e9gia para o desenvolvimento pessoal, social e profissional, garantindo os direitos conforme o Estatuto da Crian\u00e7a e do Adolescentes, Estatuto da Juventude e demais legisla\u00e7\u00f5es.<\/p>\n<p><strong>Agradecemos aos adolescentes, jovens e fam\u00edlias por acreditarem no trabalho realizado pelo Educand\u00e1rio Eur\u00edpedes.<\/strong><\/p>\n<p><strong>Agradecemos tamb\u00e9m aos nossos parceiros, Banco do Brasil, Brigestone, C\u00edrculo Militar e Villalva por garantirem o direito a Aprendizagem Profissional de adolescentes e jovens.\u00a0<\/strong>Confira como foi essa tarde de encontro e muita alegria!<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-499 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/encontro-jovem-aprendiz\/'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5277e-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-487\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5277e-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5277e-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5277e-300x300.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-487'>\n\t\t\t\tEncontro Jovem Aprendiz\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/encontro-jovem-aprendiz-2\/'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5282e-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-488\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5282e-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5282e-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5282e-300x300.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-488'>\n\t\t\t\tEncontro Jovem Aprendiz\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/encontro-jovem-aprendiz-3\/'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5284e-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-489\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5284e-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5284e-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5284e-300x300.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-489'>\n\t\t\t\tEncontro Jovem Aprendiz\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/encontro-jovem-aprendiz-4\/'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5306e-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-490\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5306e-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5306e-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5306e-300x300.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-490'>\n\t\t\t\tEncontro Jovem Aprendiz\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/encontro-jovem-aprendiz-5\/'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5317e-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-491\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5317e-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5317e-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5317e-300x300.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-491'>\n\t\t\t\tEncontro Jovem Aprendiz\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/encontro-jovem-aprendiz-6\/'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5357e-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-492\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5357e-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5357e-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5357e-300x300.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-492'>\n\t\t\t\tEncontro Jovem Aprendiz\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/encontro-jovem-aprendiz-7\/'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5376e-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-493\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5376e-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5376e-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5376e-300x300.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-493'>\n\t\t\t\tEncontro Jovem Aprendiz\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/encontro-jovem-aprendiz-8\/'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5402e-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-494\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5402e-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5402e-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5402e-300x300.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-494'>\n\t\t\t\tEncontro Jovem Aprendiz\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/encontro-jovem-aprendiz-10\/'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5413e-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-496\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5413e-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5413e-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2018\/04\/MG_5413e-300x300.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-496'>\n\t\t\t\tEncontro Jovem Aprendiz\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<hr \/>\n<p><em>Ficha t\u00e9cnica do evento:<\/em><\/p>\n<p><strong>Nome do Evento: Aprendizagem Profissional \u2013 A Garantia do Direito!<\/strong><\/p>\n<p>Data:\u00a0<strong>16 de dezembro de 2019<\/strong><\/p>\n<p>Hor\u00e1rio: das 17h \u00e0s 18h30<\/p>\n<p><strong>Respons\u00e1veis<\/strong>: Luiz Mendes, Henrique Mazzucatto e Ana L\u00edvia Rocha<\/p>\n<p>Local:\u00a0<strong>Educand\u00e1rio Eur\u00edpedes<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em conson\u00e2ncia com a Lei Federal 10.097\/2000, o\u00a0Educand\u00e1rio Eur\u00edpedes\u00a0realiza a\u00a0Aprendizagem Profissional de Adolescentes e Jovens\u00a0tendo como objetivo\u00a0\u201catender adolescentes estudantes de escola p\u00fablica, e de fam\u00edlias de baixa renda e p\u00fablico priorit\u00e1rio, possibilitando a forma\u00e7\u00e3o t\u00e9cnico-profissional met\u00f3dica compat\u00edvel com seu desenvolvimento, f\u00edsico, moral e psicol\u00f3gico respeitando sua condi\u00e7\u00e3o peculiar de pessoa em desenvolvimento\u201d. Durante o desenvolvimento [&hellip;]\n","protected":false},"author":3,"featured_media":487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[13,12,10],"_links":{"self":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/499"}],"collection":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/comments?post=499"}],"version-history":[{"count":2,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/499\/revisions"}],"predecessor-version":[{"id":501,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/499\/revisions\/501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media\/487"}],"wp:attachment":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media?parent=499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/categories?post=499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/tags?post=499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}