{"id":527,"date":"2020-01-30T16:17:53","date_gmt":"2020-01-30T19:17:53","guid":{"rendered":"https:\/\/ceak.org.br\/ee\/?p=527"},"modified":"2020-03-19T09:58:22","modified_gmt":"2020-03-19T12:58:22","slug":"ferias-convivencia-e-fortalecimento-de-vinculos","status":"publish","type":"post","link":"https:\/\/ceak.org.br\/ee\/ferias-convivencia-e-fortalecimento-de-vinculos\/","title":{"rendered":"F\u00e9rias, conviv\u00eancia e fortalecimento de v\u00ednculos"},"content":{"rendered":"<p>Em parceria com a <em>Secretaria Municipal de Assist\u00eancia Social, Pessoa com Defici\u00eancia e Direitos Humanos<\/em> da Prefeitura Municipal de Campinas, o Educand\u00e1rio Eur\u00edpedes oferta de forma gratuita e continuada o <em>Servi\u00e7o de Conviv\u00eancia e Fortalecimento de V\u00ednculos \u2013 Centro de Conviv\u00eancia Inclusivo e Intergeracional<\/em>, mais conhecido como CCII Educand\u00e1rio Eur\u00edpedes.<\/p>\n<p>Por possuir um car\u00e1ter continuado de atendimento, mesmo no <strong>m\u00eas de janeiro<\/strong>, conhecido popularmente pelo <em>\u201cm\u00eas das f\u00e9rias\u201d<\/em>, realizamos o atendimento aos adolescentes, jovens e adultos da regi\u00e3o Norte do munic\u00edpio de Campinas. <strong>Com atividades l\u00fadicas, esportivas e de lazer<\/strong>, a equipe acolheu o p\u00fablico atendido garantindo um espa\u00e7o de escuta, de conviv\u00eancia social, <em>possibilitando a amplia\u00e7\u00e3o do universo informacional, art\u00edstico e cultural<\/em> (Resolu\u00e7\u00e3o 109 \u2013 SUAS).<\/p>\n<p>O <strong>brincar, o conviver e o vivenciar<\/strong> experi\u00eancias construtivas foram as estrat\u00e9gias de trabalho da equipe para as atividades realizadas no CCII. Conforme avalia\u00e7\u00e3o de <strong>Valquiria Ferreira, pedagoga do CCII Educand\u00e1rio Eur\u00edpedes<\/strong> \u201c<em>A proposta de f\u00e9rias foi pensado em proporcionar momentos de integra\u00e7\u00e3o entre os dois per\u00edodos oferecendo um tempo de qualidade com a\u00e7\u00f5es visando fortalecer v\u00ednculos e um espa\u00e7o de conv\u00edvio e lazer, ora na institui\u00e7\u00e3o e ora nos espa\u00e7os p\u00fablicos da cidade. Usamos materiais diversificados proporcionando atividades com bola, bexigas, jogos recreativos, musicaliza\u00e7\u00e3o, games e resgastes de brincadeiras antigas, sempre incentivando o gosto pelo brincar pois entendemos que \u00e9 uma parte importante no desenvolvimento<\/em>\u201d<\/p>\n<hr \/>\n<p>Para <em><strong>Juliane Marie de Oliveira, 16 anos<\/strong><\/em>, participante das atividades do <strong>CCII Educand\u00e1rio Eur\u00edpedes,<\/strong> compartilhou um pouco do que foi esse per\u00edodo. \u201c<em>O que dizer das atividades de f\u00e9rias desse ano! Essas f\u00e9rias foram incr\u00edveis! Teve muita gincana, roda de conversas e jogos, onde trabalhamos em grupo e tivemos que aprender a trabalhar e a se comunicar com pessoas que n\u00e3o t\u00ednhamos a menor afinidade. Essas f\u00e9rias foi exatamente igual ou at\u00e9 melhor do que eu imaginava! Com muita divers\u00e3o, li\u00e7\u00e3o e o principal o apoio, ajuda e o respeito dos educadores, sem conta com toda a dedica\u00e7\u00e3o da Valquiria para que tudo ocorresse bem! As atividades externas tamb\u00e9m foram top! Nunca imaginei que poderia conhecer melhor as pessoas com gincanas e jogos, que mostram como aquela pessoa pode reagir em diferentes situa\u00e7\u00f5es, sair da zona de conforto para andar, conversar e conhecer um pouco mais das pessoas que est\u00e3o trabalhando conosco e ver que a dificuldade dele talvez seja a mesma que a sua, e voc\u00ea pode ajudar \u00e9 gratificante. Enfim o que seria dessas f\u00e9rias sem Suca, sem Val e sem o Jess\u00e9 (Equipe CCII) que j\u00e1 chegou somando e ajudando para que essas f\u00e9rias ocorresse da melhor forma poss\u00edvel! Essa de fato foi a melhor equipe que voc\u00eas poderiam ter colocado para comandar essas f\u00e9rias INCR\u00cdVEIS!<\/em>\u201d<\/p>\n<hr \/>\n<p>Desta forma, <strong>voc\u00ea que reside nos bairros da regi\u00e3o do Santa M\u00f4nica, Vila Nova, Vila Costa e Silva e Vila Miguel Vicente Cury, tem mais que 15 anos<\/strong> e ficou curioso em conhecer um pouco mais das atividades do CCII Educand\u00e1rio Eur\u00edpedes, entre em contato conosco!<\/p>\n<p><strong>As atividades acontecem de Ter\u00e7a, Quarta e Quinta-feira, no per\u00edodo da manh\u00e3 ou no per\u00edodo da tarde em nossa sede<\/strong> na Avenida Theodureto de Almeida Camargo, 750, Vila Nova, Campinas (ao lado da Bambini).<\/p>\n<p><strong>Veja um pouco sobre nossas atividades nessas f\u00e9rias! Aguardamos sua visita!\u00a0<\/strong><\/p>\n<p><em><strong>Equipe CCII Educand\u00e1rio Eur\u00edpedes<\/strong><\/em><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-527 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/ferias-convivencia-e-fortalecimento-de-vinculos\/kemily-sim\/#main'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/kemily-sim-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/kemily-sim-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/kemily-sim-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/kemily-sim-300x300.jpg 300w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/kemily-sim-600x600.jpg 600w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/ferias-convivencia-e-fortalecimento-de-vinculos\/sim-todos-tem\/#main'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/Sim-todos-tem-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/Sim-todos-tem-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/Sim-todos-tem-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/Sim-todos-tem-300x300.jpg 300w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/Sim-todos-tem-600x600.jpg 600w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ceak.org.br\/ee\/ferias-convivencia-e-fortalecimento-de-vinculos\/sim\/#main'><img width=\"340\" height=\"340\" src=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/Sim-340x340.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/Sim-340x340.jpg 340w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/Sim-180x180.jpg 180w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/Sim-300x300.jpg 300w, https:\/\/ceak.org.br\/ee\/wp-content\/uploads\/2020\/01\/Sim-600x600.jpg 600w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Em parceria com a Secretaria Municipal de Assist\u00eancia Social, Pessoa com Defici\u00eancia e Direitos Humanos da Prefeitura Municipal de Campinas, o Educand\u00e1rio Eur\u00edpedes oferta de forma gratuita e continuada o Servi\u00e7o de Conviv\u00eancia e Fortalecimento de V\u00ednculos \u2013 Centro de Conviv\u00eancia Inclusivo e Intergeracional, mais conhecido como CCII Educand\u00e1rio Eur\u00edpedes. Por possuir um car\u00e1ter continuado [&hellip;]\n","protected":false},"author":3,"featured_media":528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[14,12,9],"_links":{"self":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/527"}],"collection":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/comments?post=527"}],"version-history":[{"count":5,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/527\/revisions"}],"predecessor-version":[{"id":564,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/posts\/527\/revisions\/564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media\/528"}],"wp:attachment":[{"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/media?parent=527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/categories?post=527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceak.org.br\/ee\/wp-json\/wp\/v2\/tags?post=527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}