{"id":339,"date":"2016-07-13T22:47:17","date_gmt":"2016-07-13T22:47:17","guid":{"rendered":"http:\/\/ceak.org.br\/tudoserve\/?post_type=product&#038;p=339"},"modified":"2024-03-12T01:01:16","modified_gmt":"2024-03-12T01:01:16","slug":"fogoes","status":"publish","type":"product","link":"https:\/\/ceak.org.br\/tudoserve\/produto\/fogoes\/","title":{"rendered":"Fog\u00f5es"},"content":{"rendered":"<p>As imagens dos produtos no site Tudo Serve s\u00e3o meramente ilustrativas. As vendas\u00a0est\u00e3o condicionadas a presen\u00e7a do p\u00fablico em uma de nossas\u00a0lojas f\u00edsicas,\u00a0cabendo\u00a0ao comprador a livre op\u00e7\u00e3o de compra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>a partir de:<\/p>\n<h2>R$ 100,00<\/h2>\n<p>Aten\u00e7\u00e3o: A\u00a0efetiva\u00e7\u00e3o da compra est\u00e1\u00a0condicionada\u00a0\u00e0 loja f\u00edsica.\u00a0Voc\u00ea pode efetuar uma reserva por telefone por tempo limitado.<\/p>\n<a href=\"tel:+551925148774\" class=\"button medium primary\" >FA\u00c7A SUA RESERVA (19) 2514-8774<\/a>\n<p>Entre em contato para obter mais detalhes sobre os produtos.<\/p>\n","protected":false},"featured_media":452,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/ceak.org.br\/tudoserve\/wp-json\/wp\/v2\/product\/339"}],"collection":[{"href":"https:\/\/ceak.org.br\/tudoserve\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ceak.org.br\/tudoserve\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/tudoserve\/wp-json\/wp\/v2\/comments?post=339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceak.org.br\/tudoserve\/wp-json\/wp\/v2\/media\/452"}],"wp:attachment":[{"href":"https:\/\/ceak.org.br\/tudoserve\/wp-json\/wp\/v2\/media?parent=339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}